{"id":57580,"date":"2024-02-03T03:24:32","date_gmt":"2024-02-03T03:24:32","guid":{"rendered":"https:\/\/www.supportedemployment.ca\/?post_type=product&#038;p=57580"},"modified":"2024-02-03T03:26:34","modified_gmt":"2024-02-03T03:26:34","slug":"digital-literacy-instructor-certificate-program","status":"publish","type":"product","link":"https:\/\/www.supportedemployment.ca\/fr\/shop\/certificate-programs\/digital-literacy-instructor-certificate-program\/","title":{"rendered":"Programme de certificat d'instructeur en litt\u00e9ratie num\u00e9rique"},"content":{"rendered":"<div class=\"elementor-element elementor-element-bb933b6 elementor-widget elementor-widget-text-editor\" data-id=\"bb933b6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<div class=\"e5948-15 x-text\"><span class=\"TextRun SCXW129301402 BCX0\" lang=\"EN-CA\" xml:lang=\"EN-CA\" data-contrast=\"none\"><span class=\"NormalTextRun SCXW129301402 BCX0\">La litt\u00e9ratie num\u00e9rique est reconnue comme une comp\u00e9tence essentielle<\/span><span class=\"NormalTextRun SCXW129301402 BCX0\">jouer<\/span><span class=\"NormalTextRun SCXW129301402 BCX0\">\u00a0qui soutient l'apprentissage tout au long de la vie et augmente l'employabilit\u00e9.\u00a0<\/span><span class=\"NormalTextRun SCXW129301402 BCX0\">La main-d'\u0153uvre canadienne est\u00a0<\/span><span class=\"NormalTextRun SCXW129301402 BCX0\">exp\u00e9rimentant\u00a0<\/span><span class=\"NormalTextRun SCXW129301402 BCX0\">expon<\/span><span class=\"NormalTextRun SCXW129301402 BCX0\">croissance exponentielle de l'utilisation des plateformes, applications et outils num\u00e9riques.\u00a0<\/span><span class=\"NormalTextRun SCXW129301402 BCX0\">Dans ce march\u00e9 du travail en constante \u00e9volution, de nombreux\u00a0<\/span><span class=\"NormalTextRun SCXW129301402 BCX0\">chercheurs d'emploi et nouveaux employ\u00e9s<\/span><span class=\"NormalTextRun SCXW129301402 BCX0\">employ\u00e9s\u00a0<\/span><span class=\"NormalTextRun SCXW129301402 BCX0\">sont requis<\/span><span class=\"NormalTextRun SCXW129301402 BCX0\">rouge \u00e0<\/span><span class=\"NormalTextRun SCXW129301402 BCX0\">\u00a0utiliser la technologie pour\u00a0<\/span><span class=\"NormalTextRun SCXW129301402 BCX0\">rechercher, communiquer et accomplir des t\u00e2ches li\u00e9es au travail\u00a0<\/span><span class=\"NormalTextRun SCXW129301402 BCX0\">t\u00e2ches<\/span><span class=\"NormalTextRun SCXW129301402 BCX0\">.<\/span><\/span><span class=\"EOP SCXW129301402 BCX0\" data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\"><br \/>\n<\/span><\/div>\n<\/div>\n<div>\n<div class=\"elementor-element elementor-element-69c7e52 elementor-widget elementor-widget-text-editor\" data-id=\"69c7e52\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p>Ce programme en ligne pr\u00e9pare les conseillers en emploi \u00e0 mener des \u00e9valuations des comp\u00e9tences num\u00e9riques. Il fournit les outils et les ressources n\u00e9cessaires pour aider les chercheurs d'emploi \u00e0 am\u00e9liorer leurs connaissances num\u00e9riques et leurs comp\u00e9tences techniques. Le programme favorise la pens\u00e9e critique en mati\u00e8re de s\u00e9curit\u00e9 en ligne en explorant des strat\u00e9gies pour g\u00e9rer sa pr\u00e9sence en ligne et exploiter les m\u00e9dias sociaux \u00e0 des fins professionnelles.<\/p>\n<p>Le programme de certification de l'instructeur en litt\u00e9ratie num\u00e9rique permet aux prestataires de services d'emploi d'offrir une formation et un soutien complets aux chercheurs d'emploi. Lorsqu'un professionnel de l'emploi termine avec succ\u00e8s le programme, il est \u00e9ligible pour :<\/p>\n<ul>\n<li>recevoir une URL d'inscription et une orientation pour l'instructeur,<\/li>\n<li>h\u00e9berger un groupe d'\u00e9tudiants sur le portail d'apprentissage CASE,<\/li>\n<li>noter les devoirs et donner un retour aux \u00e9tudiants,<\/li>\n<li>recevoir les donn\u00e9es d'\u00e9valuation de leurs \u00e9tudiants, et<\/li>\n<li>acc\u00e9der au support technique pendant l'enseignement.<\/li>\n<\/ul>\n<div class=\"elementor-element elementor-element-89d0b6a elementor-widget elementor-widget-text-editor\" data-id=\"89d0b6a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n<div class=\"elementor-widget-container\">\n<p><span data-contrast=\"none\">\u00c0 l'issue de leur participation respective aux programmes, les instructeurs et les demandeurs d'emploi re\u00e7oivent des micro-certifications qui attestent de leur implication et d\u00e9crivent les connaissances, comp\u00e9tences et\/ou aptitudes cibl\u00e9es qui ont \u00e9t\u00e9 abord\u00e9es.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p>Les programmes de certificat en litt\u00e9ratie num\u00e9rique ont \u00e9t\u00e9 \u00e9labor\u00e9s en partenariat avec la University of the Fraser Valley, avec le soutien suppl\u00e9mentaire de Community Futures South Fraser, Community Futures Ventures et le programme Entrepreneurs with Disabilities Program of BC.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Digital literacy is recognized as a critical skillset\u00a0that supports life-long learning and increases employability.\u00a0The Canadian workforce is\u00a0experiencing\u00a0exponential growth in the use of digital platforms, applications, and tools.\u00a0In this evolving labour [&hellip;]<\/p>\n","protected":false},"featured_media":57133,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[333],"product_tag":[],"class_list":["post-57580","product","type-product","status-publish","has-post-thumbnail","product_cat-certificate-programs","first","instock","virtual","taxable","purchasable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.supportedemployment.ca\/fr\/wp-json\/wp\/v2\/product\/57580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.supportedemployment.ca\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.supportedemployment.ca\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.supportedemployment.ca\/fr\/wp-json\/wp\/v2\/comments?post=57580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.supportedemployment.ca\/fr\/wp-json\/wp\/v2\/media\/57133"}],"wp:attachment":[{"href":"https:\/\/www.supportedemployment.ca\/fr\/wp-json\/wp\/v2\/media?parent=57580"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.supportedemployment.ca\/fr\/wp-json\/wp\/v2\/product_brand?post=57580"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.supportedemployment.ca\/fr\/wp-json\/wp\/v2\/product_cat?post=57580"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.supportedemployment.ca\/fr\/wp-json\/wp\/v2\/product_tag?post=57580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}