{"id":62133,"date":"2026-03-27T17:16:30","date_gmt":"2026-03-27T21:16:30","guid":{"rendered":"https:\/\/www.supportedemployment.ca\/?page_id=62133"},"modified":"2026-06-24T12:11:01","modified_gmt":"2026-06-24T16:11:01","slug":"building-social-capital","status":"publish","type":"page","link":"https:\/\/www.supportedemployment.ca\/fr\/training-and-events\/courses\/building-social-capital\/","title":{"rendered":"D\u00e9velopper son capital social"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"62133\" class=\"elementor elementor-62133\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f391220 elementor-section-full_width elementor-section-height-min-height elementor-section-items-bottom elementor-section-height-default\" data-id=\"2f391220\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f445905\" data-id=\"f445905\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d476a79 elementor-widget elementor-widget-heading\" data-id=\"6d476a79\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">D\u00e9velopper son capital social<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4dbc7f88 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"4dbc7f88\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-518bf087\" data-id=\"518bf087\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1c1d5365 elementor-widget elementor-widget-shortcode\" data-id=\"1c1d5365\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><nav aria-label=\"chapelure\" class=\"rank-math-breadcrumb\"><p><span class=\"last\">Accueil<\/span><\/p><\/nav><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-457037d3 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"457037d3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-4513d553\" data-id=\"4513d553\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78295cfa elementor-widget elementor-widget-image\" data-id=\"78295cfa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/www.supportedemployment.ca\/wp-content\/uploads\/2026\/03\/iStock-2194386980-1024x683.jpg\" class=\"attachment-large size-large wp-image-62134\" alt=\"\" srcset=\"https:\/\/www.supportedemployment.ca\/wp-content\/uploads\/2026\/03\/iStock-2194386980-1024x683.jpg 1024w, https:\/\/www.supportedemployment.ca\/wp-content\/uploads\/2026\/03\/iStock-2194386980-300x200.jpg 300w, https:\/\/www.supportedemployment.ca\/wp-content\/uploads\/2026\/03\/iStock-2194386980-768x512.jpg 768w, https:\/\/www.supportedemployment.ca\/wp-content\/uploads\/2026\/03\/iStock-2194386980-600x400.jpg 600w, https:\/\/www.supportedemployment.ca\/wp-content\/uploads\/2026\/03\/iStock-2194386980.jpg 1253w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Un groupe de personnes portant des badges d'identification et discutant, repr\u00e9sentant un \u00e9v\u00e9nement de r\u00e9seautage o\u00f9 les gens peuvent b\u00e2tir leur capital social.\u00a0<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-613152d1\" data-id=\"613152d1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3af7d95c elementor-widget elementor-widget-heading\" data-id=\"3af7d95c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">D\u00e9velopper son capital social<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20cb46b4 elementor-widget elementor-widget-text-editor\" data-id=\"20cb46b4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Repensez \u00e0 votre vie et \u00e0 votre carri\u00e8re. Comment votre entourage vous a-t-il soutenu pour vous permettre d'en arriver l\u00e0 o\u00f9 vous \u00eates aujourd'hui  ?<\/p><p>Ce soutien s'appelle le capital social. Le capital social favorise la carri\u00e8re, l'apprentissage et l'acc\u00e8s aux ressources et \u00e0 l'emploi. Ceci \u00e9tant dit, les personnes en situation de handicap qui recherchent un emploi peuvent rencontrer des obstacles lorsque vient le temps de d\u00e9velopper leur capital social. Ce cours de formation propose des approches efficaces pour aider votre client\u00e8le \u00e0 surmonter ces obstacles !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-37104293 elementor-widget elementor-widget-heading\" data-id=\"37104293\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ce que vous apprendrez<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d63aef elementor-widget elementor-widget-text-editor\" data-id=\"3d63aef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"e9167-24 x-text\"><ul><li>Des recherches sur la valeur et les diff\u00e9rentes composantes du capital social.<\/li><li>Les obstacles que peuvent rencontrer les personnes en situation de handicap qui recherchent un emploi pour se constituer un r\u00e9seau solide.<\/li><li>Des moyens d'aider les personnes en situation de handicap \u00e0 la recherche d'un emploi \u00e0 identifier et \u00e0 exploiter leur capital social actuel.<\/li><li>Des pratiques pour d\u00e9velopper son capital social, telles la cartographie des ressources, le mentorat et le r\u00e9seautage sur les r\u00e9seaux sociaux.<\/li><\/ul><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c3b095 elementor-widget elementor-widget-heading\" data-id=\"7c3b095\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Prestation de cours<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-371d5b48 elementor-widget elementor-widget-text-editor\" data-id=\"371d5b48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div>Cette formation est dispens\u00e9e en ligne. Vous pouvez la compl\u00e9ter \u00e0 votre rythme en environ 2 heures. Les personnes participantes ayant r\u00e9ussi recevront des microcertifications. Ces microcertifications comprennent un badge et un certificat num\u00e9riques que vous pouvez partager sur les r\u00e9seaux sociaux.<\/div><div>\u00a0<\/div><div class=\"translation-block\">Cette formation est dispens\u00e9e en ligne. Vous pouvez la compl\u00e9ter \u00e0 votre rythme en environ 2 heures. Les personnes participantes ayant r\u00e9ussi recevront des microcertifications. Ces microcertifications comprennent un badge et un certificat num\u00e9riques que vous pouvez partager sur les r\u00e9seaux sociaux.<br><br>\nVous pouvez vous inscrire sur <a href=\"https:\/\/learn.supportedemployment.ca\/course\/developper-son-capital-social\" target=\"_blank\" rel=\"noopener\">le portail d'apprentissage de l'ACSE<\/a> et commencer quand vous le voulez. Pour toute question ou aide, contactez-nous \u00e0  : <a href=\"mailto:learn@supportedemployment.ca\" target=\"_self\">learn@supportedemployment.ca<\/a>.<\/div><div>\u00a0<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2865457 elementor-widget elementor-widget-heading\" data-id=\"2865457\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Inscrivez-vous maintenant<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8b0719 elementor-align-left elementor-widget elementor-widget-button\" data-id=\"c8b0719\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/learn.supportedemployment.ca\/course\/developper-son-capital-social\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Cliquez ici pour vous inscrire \u00e0 cette formation.<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6bf1318 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6bf1318\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c84d703\" data-id=\"c84d703\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-378219bf elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"378219bf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4d22e3b0\" data-id=\"4d22e3b0\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-654ba97d elementor-widget elementor-widget-heading\" data-id=\"654ba97d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Infolettre<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6045d71e elementor-widget elementor-widget-text-editor\" data-id=\"6045d71e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ne manquez pas les derni\u00e8res nouvelles de l\u2019ACSE et du soutien \u00e0 l\u2019emploi partout au Canada et ailleurs en vous inscrivant \u00e0 notre infolettre. Vous recevrez \u00e9galement nos plus r\u00e9centes offres et promotions. Nous ne partagerons pas votre adresse courriel \u00e0 des fournisseurs tiers. Consultez notre Politique de confidentialit\u00e9 pour des d\u00e9tails complets sur la fa\u00e7on dont nous prot\u00e9geons vos renseignements personnels.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3530573d elementor-align-left elementor-widget elementor-widget-button\" data-id=\"3530573d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/supportedemployment.us1.list-manage.com\/subscribe?u=fc35f270c6cd01b628bbbe92b&amp;id=34e9712bc7\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Abonnez-vous \u00e0 l\u2019infolettre de l\u2019ACSE<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4530de16\" data-id=\"4530de16\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31f1e156 elementor-widget elementor-widget-heading\" data-id=\"31f1e156\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contactez l'ACSE<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65a558c8 elementor-widget elementor-widget-text-editor\" data-id=\"65a558c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Parlez-nous des initiatives nouvelles et innovatrices que pilote pr\u00e9sentement votre organisation en mati\u00e8re d\u2019emploi. Faites-nous part de vos id\u00e9es ou vos conseils sur la fa\u00e7on dont l\u2019ACSE peut mieux vous servir.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93be55d elementor-align-left elementor-widget elementor-widget-button\" data-id=\"93be55d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.supportedemployment.ca\/fr\/contact-us\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Communiquez avec nous.<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Building Social Capital A group of people wearing identity\u00a0cards and talking,\u00a0representing\u00a0a networking event where people can build their social capital.\u00a0 Building Social Capital Think back on your life and career. [&hellip;]<\/p>\n","protected":false},"author":3633,"featured_media":0,"parent":15999,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-62133","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.supportedemployment.ca\/fr\/wp-json\/wp\/v2\/pages\/62133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.supportedemployment.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.supportedemployment.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.supportedemployment.ca\/fr\/wp-json\/wp\/v2\/users\/3633"}],"replies":[{"embeddable":true,"href":"https:\/\/www.supportedemployment.ca\/fr\/wp-json\/wp\/v2\/comments?post=62133"}],"version-history":[{"count":1,"href":"https:\/\/www.supportedemployment.ca\/fr\/wp-json\/wp\/v2\/pages\/62133\/revisions"}],"predecessor-version":[{"id":62542,"href":"https:\/\/www.supportedemployment.ca\/fr\/wp-json\/wp\/v2\/pages\/62133\/revisions\/62542"}],"up":[{"embeddable":true,"href":"https:\/\/www.supportedemployment.ca\/fr\/wp-json\/wp\/v2\/pages\/15999"}],"wp:attachment":[{"href":"https:\/\/www.supportedemployment.ca\/fr\/wp-json\/wp\/v2\/media?parent=62133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}